{"id":77431,"date":"2024-04-11T20:38:40","date_gmt":"2024-04-11T18:38:40","guid":{"rendered":"https:\/\/montecarlotennismasters.com\/?p=77431"},"modified":"2024-04-11T20:38:40","modified_gmt":"2024-04-11T18:38:40","slug":"rune-al-suo-massimo-sforzo","status":"publish","type":"post","link":"https:\/\/montecarlotennismasters.com\/it\/rune-al-suo-massimo-sforzo\/","title":{"rendered":"Rune, al suo massimo sforzo"},"content":{"rendered":"<p>Ha trascorso oltre 4 ore e mezza in campo oggi, ma \u00e8 ancora vivo. Dopo una dura lotta contro Grigor Dimitrov, Holger Rune si \u00e8 finalmente qualificato per i quarti di finale di questa 117\u00b0 edizione del Rolex Monte-Carlo Masters (7-6, 3-6, 7-6).<\/p>\n<p>Questo gioved\u00ec mattina, il danese doveva gi\u00e0 terminare il suo match contro il Summit Nagal, interrotto il giorno prima a causa della pioggia. Il match riprende sul 6-3, break di 2-1 per Rune, ma quest&#8217;ultimo, per una stupida imprecisione, si lascia scappare il set. Ma di fronte al primo indiano della storia a vincere una partita del Masters 1000 sulla terra battuta, il numero 7 del mondo \u00e8 riuscito ad alzare il suo livello nei mometni chiave per arrivare a un risultato a suo favore.<\/p>\n<p>Ma la giornata non \u00e9 ancora finita. Holger Rune gioca ancora gli ottavi di finale contro Grigor Dimitrov, che poche ore prima aveva sconfitto anche Kecmanovic. Una cosa \u00e8 certa: entrambi avevano ancora tanto da dire e da fare.<\/p>\n<p>Il primo set si \u00e8 concluso al tie break, dopo pi\u00f9 di un&#8217;ora e mezza, 11-9 a favore del danese nella partita decisiva. Ma Dimitrov non aveva detto la sua ultima parola. Con il break immediato nel secondo set, \u00e9 riuscito comunque a vincerlo, in 45 minuti. Inesauribile, l&#8217;ex numero 3 infila colpi spettacolari, come spettacolare \u00e9 il suo twiner. E il pubblico chiede ancora di pi\u00f9. 6-3 per il bulgaro e gi\u00e0 pi\u00f9 di due ore di gioco.Il terzo set \u00e8 come la partita: irrespirabile. Dopo aver salvato due match point sul 5-6, Holger Rune \u00e8 riuscito a fare la differenza nel tie break vinto 7-1. \u201c<em>Grigor \u00e8 uno dei talenti pi\u00f9 incredibili del circuito. Sono molto felice di averlo battuto, anche se \u00e8 stato molto difficile\u201d<\/em>, ha sottolineato H. Rune alla fine della sua vittoria.<\/p>\n<p>Venerd\u00ec il compito si preannuncia altrettanto arduo. Il finalista della scorsa edizione affronter\u00e0 l&#8217;uomo del momento, vincitore dell&#8217;ultimo Australian Open, Jannik Sinner. Quest&#8217;ultimo ha impiegato solo 1h16 per liberarsi di Jan-Lennard Struff questo pomeriggio. \u201c<em>Sar\u00e0 fantastico. Vedremo come va. Nessuno l\u2019ha ancora battuto questa stagione, sar\u00e0 una grande sfida soprattutto dopo la maratona di oggi. Per ora penso soprattutto a recuperare\u201d<\/em>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Danese si qualifica ai quarti di finale dopo il combattimento dantesco contro Grigor Dimitrov (7-6, 3-6, 7-6)<\/p>\n","protected":false},"author":20,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-77431","post","type-post","status-publish","format-standard","hentry","category-non-classifiee-it"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rune, al suo massimo sforzo - Rolex Monte-Carlo Masters<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/montecarlotennismasters.com\/it\/rune-al-suo-massimo-sforzo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rune, al suo massimo sforzo - Rolex Monte-Carlo Masters\" \/>\n<meta property=\"og:description\" content=\"Il Danese si qualifica ai quarti di finale dopo il combattimento dantesco contro Grigor Dimitrov (7-6, 3-6, 7-6)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/montecarlotennismasters.com\/it\/rune-al-suo-massimo-sforzo\/\" \/>\n<meta property=\"og:site_name\" content=\"Rolex Monte-Carlo Masters\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-11T18:38:40+00:00\" \/>\n<meta name=\"author\" content=\"Giorgia ROSSI\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Giorgia ROSSI\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/rune-al-suo-massimo-sforzo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/rune-al-suo-massimo-sforzo\\\/\"},\"author\":{\"name\":\"Giorgia ROSSI\",\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/#\\\/schema\\\/person\\\/e6ec56124b19f27d40fe89aa9286ec0a\"},\"headline\":\"Rune, al suo massimo sforzo\",\"datePublished\":\"2024-04-11T18:38:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/rune-al-suo-massimo-sforzo\\\/\"},\"wordCount\":360,\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/rune-al-suo-massimo-sforzo\\\/\",\"url\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/rune-al-suo-massimo-sforzo\\\/\",\"name\":\"Rune, al suo massimo sforzo - Rolex Monte-Carlo Masters\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/#website\"},\"datePublished\":\"2024-04-11T18:38:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/#\\\/schema\\\/person\\\/e6ec56124b19f27d40fe89aa9286ec0a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/rune-al-suo-massimo-sforzo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/rune-al-suo-massimo-sforzo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/rune-al-suo-massimo-sforzo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rune, al suo massimo sforzo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/#website\",\"url\":\"https:\\\/\\\/montecarlotennismasters.com\\\/\",\"name\":\"Rolex Monte-Carlo Masters\",\"description\":\"11-19 aprile 2020\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/montecarlotennismasters.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/#\\\/schema\\\/person\\\/e6ec56124b19f27d40fe89aa9286ec0a\",\"name\":\"Giorgia ROSSI\",\"url\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/author\\\/grossi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rune, al suo massimo sforzo - Rolex Monte-Carlo Masters","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/montecarlotennismasters.com\/it\/rune-al-suo-massimo-sforzo\/","og_locale":"it_IT","og_type":"article","og_title":"Rune, al suo massimo sforzo - Rolex Monte-Carlo Masters","og_description":"Il Danese si qualifica ai quarti di finale dopo il combattimento dantesco contro Grigor Dimitrov (7-6, 3-6, 7-6)","og_url":"https:\/\/montecarlotennismasters.com\/it\/rune-al-suo-massimo-sforzo\/","og_site_name":"Rolex Monte-Carlo Masters","article_published_time":"2024-04-11T18:38:40+00:00","author":"Giorgia ROSSI","twitter_misc":{"Scritto da":"Giorgia ROSSI","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/montecarlotennismasters.com\/it\/rune-al-suo-massimo-sforzo\/#article","isPartOf":{"@id":"https:\/\/montecarlotennismasters.com\/it\/rune-al-suo-massimo-sforzo\/"},"author":{"name":"Giorgia ROSSI","@id":"https:\/\/montecarlotennismasters.com\/#\/schema\/person\/e6ec56124b19f27d40fe89aa9286ec0a"},"headline":"Rune, al suo massimo sforzo","datePublished":"2024-04-11T18:38:40+00:00","mainEntityOfPage":{"@id":"https:\/\/montecarlotennismasters.com\/it\/rune-al-suo-massimo-sforzo\/"},"wordCount":360,"articleSection":["Non classifi\u00e9(e)"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/montecarlotennismasters.com\/it\/rune-al-suo-massimo-sforzo\/","url":"https:\/\/montecarlotennismasters.com\/it\/rune-al-suo-massimo-sforzo\/","name":"Rune, al suo massimo sforzo - Rolex Monte-Carlo Masters","isPartOf":{"@id":"https:\/\/montecarlotennismasters.com\/#website"},"datePublished":"2024-04-11T18:38:40+00:00","author":{"@id":"https:\/\/montecarlotennismasters.com\/#\/schema\/person\/e6ec56124b19f27d40fe89aa9286ec0a"},"breadcrumb":{"@id":"https:\/\/montecarlotennismasters.com\/it\/rune-al-suo-massimo-sforzo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/montecarlotennismasters.com\/it\/rune-al-suo-massimo-sforzo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/montecarlotennismasters.com\/it\/rune-al-suo-massimo-sforzo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/montecarlotennismasters.com\/it\/"},{"@type":"ListItem","position":2,"name":"Rune, al suo massimo sforzo"}]},{"@type":"WebSite","@id":"https:\/\/montecarlotennismasters.com\/#website","url":"https:\/\/montecarlotennismasters.com\/","name":"Rolex Monte-Carlo Masters","description":"11-19 aprile 2020","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/montecarlotennismasters.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/montecarlotennismasters.com\/#\/schema\/person\/e6ec56124b19f27d40fe89aa9286ec0a","name":"Giorgia ROSSI","url":"https:\/\/montecarlotennismasters.com\/it\/author\/grossi\/"}]}},"_links":{"self":[{"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/posts\/77431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/comments?post=77431"}],"version-history":[{"count":0,"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/posts\/77431\/revisions"}],"wp:attachment":[{"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/media?parent=77431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/categories?post=77431"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/tags?post=77431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}