{"id":85496,"date":"2025-04-08T15:16:15","date_gmt":"2025-04-08T13:16:15","guid":{"rendered":"https:\/\/montecarlotennismasters.com\/?p=85496"},"modified":"2025-04-08T15:16:15","modified_gmt":"2025-04-08T13:16:15","slug":"dimitrov-unaltra-volta-avversario-di-vacherot","status":"publish","type":"post","link":"https:\/\/montecarlotennismasters.com\/it\/dimitrov-unaltra-volta-avversario-di-vacherot\/","title":{"rendered":"Dimitrov un&#8217;altra volta avversario di Vacherot"},"content":{"rendered":"<p style=\"text-align: justify;\">\u00c8 difficile immaginare quanto sia complicato concludere un match di tennis. Per segnare quel famoso ultimo punto prima di levare le braccia, e di andare a stringere la mano all&#8217;avversario e passare alla partita successiva.<\/p>\n<p style=\"text-align: justify;\">Mantenendo il controllo per oltre un&#8217;ora sul Campo Rainier III, in apertura questo marted\u00ec, Grigor Dimitrov sembrava destinato ad una facile vittoria contro Nicolas Jarry. Era in vantaggio per 6-3, 3-0 con doppio break, controllava gli scambi, segnava il ritmo della partita, grazie ad un potente primo servizio. Per la sua prima partita su terra rossa in 10 mesi, appena pochi giorni dopo aver giocato la semifinale del Masters 1000 di Miami (battuto da Djokovic), faceva veramente un&#8217;ottima figura.<\/p>\n<p style=\"text-align: justify;\">Ma il cileno gli ha spesso causato problemi, vincendo due dei tre precedenti incontri, ogni volta sulla terra battuta, inclusa una finale a Ginevra nel 2023. &#8220;<em>Me lo ricordavo<\/em>&#8220;, dichiara Dimitrov<em>. Solo sul cemento sono riuscito a batterlo, a Shanghai.<\/em> \u00bb Ma Jarry non si arrende, commette sempre meno errori e costringe Dimitrov ad arretrare leggermente. Un primo break, poi un match point salvato sul 5-3 e costringe Dimitrov a servire per il match sul 5-4.<\/p>\n<p style=\"text-align: justify;\">Una partita emozionante, in cui Dimitrov conquista almeno \u00a05 nuovi match point, quasi tutti falli diretti. Improvvisamente senza un primo servizio (tranne un ace a 215 km\/h servito per annullare il punto del 5-5), il bulgaro ha avuto moltissima difficolt\u00e0 per concludere il match. Ma ci riesce comunque al settimo tentativo, costringendo Jarry a sbagliare al termine di un lunghissimo scambio.<\/p>\n<p style=\"text-align: justify;\">Domani, la testa di serie numero 15 affronter\u00e0 il monegasco Valentin Vacherot, che ha battuto per 7-5, 6-2 nel 2024 al Rolex Monte-Carlo Masters. &#8220;<em>Mi alleno spesso qui al MC.C.C.C. Conosco bene i campi, ma lui li conosce ancora meglio&#8221;<\/em>, ha detto scherzando Dimitrov. <em>E poi avr\u00e0 tutti i suoi fan, la squadra della Coppa Davis di Monaco. Ma \u00e8 normale. Per me, in definitiva, sar\u00e0 una partita contro un qualsiasi altro avversario.<\/em> \u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>VIttorioso contro Jarry (6-3, 6-4 in 1h46), il Bulgaro affronter\u00e0 il Monegasco, come l&#8217;anno scorso, al turno seguente.<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-85496","post","type-post","status-publish","format-standard","hentry","category-non-classifiee-it"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dimitrov un&#039;altra volta avversario di Vacherot - Rolex Monte-Carlo Masters<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/montecarlotennismasters.com\/it\/dimitrov-unaltra-volta-avversario-di-vacherot\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dimitrov un&#039;altra volta avversario di Vacherot - Rolex Monte-Carlo Masters\" \/>\n<meta property=\"og:description\" content=\"VIttorioso contro Jarry (6-3, 6-4 in 1h46), il Bulgaro affronter\u00e0 il Monegasco, come l&#039;anno scorso, al turno seguente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/montecarlotennismasters.com\/it\/dimitrov-unaltra-volta-avversario-di-vacherot\/\" \/>\n<meta property=\"og:site_name\" content=\"Rolex Monte-Carlo Masters\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-08T13:16:15+00:00\" \/>\n<meta name=\"author\" content=\"Eric SILVESTRO\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eric SILVESTRO\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/dimitrov-unaltra-volta-avversario-di-vacherot\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/dimitrov-unaltra-volta-avversario-di-vacherot\\\/\"},\"author\":{\"name\":\"Eric SILVESTRO\",\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/#\\\/schema\\\/person\\\/2ba3ea68fef415c502ae40903053fada\"},\"headline\":\"Dimitrov un&#8217;altra volta avversario di Vacherot\",\"datePublished\":\"2025-04-08T13:16:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/dimitrov-unaltra-volta-avversario-di-vacherot\\\/\"},\"wordCount\":328,\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/dimitrov-unaltra-volta-avversario-di-vacherot\\\/\",\"url\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/dimitrov-unaltra-volta-avversario-di-vacherot\\\/\",\"name\":\"Dimitrov un'altra volta avversario di Vacherot - Rolex Monte-Carlo Masters\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/#website\"},\"datePublished\":\"2025-04-08T13:16:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/#\\\/schema\\\/person\\\/2ba3ea68fef415c502ae40903053fada\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/dimitrov-unaltra-volta-avversario-di-vacherot\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/dimitrov-unaltra-volta-avversario-di-vacherot\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/dimitrov-unaltra-volta-avversario-di-vacherot\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dimitrov un&rsquo;altra volta avversario di Vacherot\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/#website\",\"url\":\"https:\\\/\\\/montecarlotennismasters.com\\\/\",\"name\":\"Rolex Monte-Carlo Masters\",\"description\":\"11-19 aprile 2020\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/montecarlotennismasters.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/#\\\/schema\\\/person\\\/2ba3ea68fef415c502ae40903053fada\",\"name\":\"Eric SILVESTRO\",\"url\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/author\\\/esilvestro\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dimitrov un'altra volta avversario di Vacherot - Rolex Monte-Carlo Masters","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/montecarlotennismasters.com\/it\/dimitrov-unaltra-volta-avversario-di-vacherot\/","og_locale":"it_IT","og_type":"article","og_title":"Dimitrov un'altra volta avversario di Vacherot - Rolex Monte-Carlo Masters","og_description":"VIttorioso contro Jarry (6-3, 6-4 in 1h46), il Bulgaro affronter\u00e0 il Monegasco, come l'anno scorso, al turno seguente.","og_url":"https:\/\/montecarlotennismasters.com\/it\/dimitrov-unaltra-volta-avversario-di-vacherot\/","og_site_name":"Rolex Monte-Carlo Masters","article_published_time":"2025-04-08T13:16:15+00:00","author":"Eric SILVESTRO","twitter_misc":{"Scritto da":"Eric SILVESTRO","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/montecarlotennismasters.com\/it\/dimitrov-unaltra-volta-avversario-di-vacherot\/#article","isPartOf":{"@id":"https:\/\/montecarlotennismasters.com\/it\/dimitrov-unaltra-volta-avversario-di-vacherot\/"},"author":{"name":"Eric SILVESTRO","@id":"https:\/\/montecarlotennismasters.com\/#\/schema\/person\/2ba3ea68fef415c502ae40903053fada"},"headline":"Dimitrov un&#8217;altra volta avversario di Vacherot","datePublished":"2025-04-08T13:16:15+00:00","mainEntityOfPage":{"@id":"https:\/\/montecarlotennismasters.com\/it\/dimitrov-unaltra-volta-avversario-di-vacherot\/"},"wordCount":328,"articleSection":["Non classifi\u00e9(e)"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/montecarlotennismasters.com\/it\/dimitrov-unaltra-volta-avversario-di-vacherot\/","url":"https:\/\/montecarlotennismasters.com\/it\/dimitrov-unaltra-volta-avversario-di-vacherot\/","name":"Dimitrov un'altra volta avversario di Vacherot - Rolex Monte-Carlo Masters","isPartOf":{"@id":"https:\/\/montecarlotennismasters.com\/#website"},"datePublished":"2025-04-08T13:16:15+00:00","author":{"@id":"https:\/\/montecarlotennismasters.com\/#\/schema\/person\/2ba3ea68fef415c502ae40903053fada"},"breadcrumb":{"@id":"https:\/\/montecarlotennismasters.com\/it\/dimitrov-unaltra-volta-avversario-di-vacherot\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/montecarlotennismasters.com\/it\/dimitrov-unaltra-volta-avversario-di-vacherot\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/montecarlotennismasters.com\/it\/dimitrov-unaltra-volta-avversario-di-vacherot\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/montecarlotennismasters.com\/it\/"},{"@type":"ListItem","position":2,"name":"Dimitrov un&rsquo;altra volta avversario di Vacherot"}]},{"@type":"WebSite","@id":"https:\/\/montecarlotennismasters.com\/#website","url":"https:\/\/montecarlotennismasters.com\/","name":"Rolex Monte-Carlo Masters","description":"11-19 aprile 2020","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/montecarlotennismasters.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/montecarlotennismasters.com\/#\/schema\/person\/2ba3ea68fef415c502ae40903053fada","name":"Eric SILVESTRO","url":"https:\/\/montecarlotennismasters.com\/it\/author\/esilvestro\/"}]}},"_links":{"self":[{"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/posts\/85496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/comments?post=85496"}],"version-history":[{"count":0,"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/posts\/85496\/revisions"}],"wp:attachment":[{"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/media?parent=85496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/categories?post=85496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/tags?post=85496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}