{"id":85944,"date":"2025-04-09T19:03:39","date_gmt":"2025-04-09T17:03:39","guid":{"rendered":"https:\/\/montecarlotennismasters.com\/?p=85944"},"modified":"2025-04-09T19:03:39","modified_gmt":"2025-04-09T17:03:39","slug":"rublev-riesce-a-piegare-monfils","status":"publish","type":"post","link":"https:\/\/montecarlotennismasters.com\/it\/rublev-riesce-a-piegare-monfils\/","title":{"rendered":"Rublev riesce a piegare Monfils"},"content":{"rendered":"<p style=\"text-align: justify;\">Mercoled\u00ec al Rolex Monte-Carlo Masters era come stare in il &#8220;Ritorno al futuro&#8221;. Mentre Richard Gasquet salutava il pubblico del Campo Rainier III, 23 anni dopo aver stupito il mondo a nemmeno 16 anni giocando un indimenticabile secondo turno contro Marat Safin, il russo guardava dalla prima fila sugli spalti del Campo dei Principi, sempre in tuta, ormai consigliere di Andrej Rublev, davanti a Ga\u00ebl Monfils che stava giocando. E a testimonoanza del passare del tempo, Safin si \u00e8 messo proprio lungo la linea di fondo, ormai spodestato nelle sue funzioni di giudice, dall\u2019intelligenza artificiale e da una serie di telecamere e altri sensori che segnalano le palle fuori campo. Per un attimo abbiamo temuto che Safin allungasse il braccio per indicare una palla lunga.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Rublev \u2013 Monfils sul campo dei Principi, un\u2019ulteriore dimostrazione dell\u2019altissimo livello di questo primo Masters 1000 della stagione su terra battuta. Il commento di Arthur Fils, deluso di non aver potuto affrontare il suo &#8220;fratello maggiore&#8221; Ga\u00ebl Monfils, quando l\u2019ha incrociato in sala stampa: &#8220;<em>Ero un po&#8217; deluso di essere stato assegnato al terzo campo \u2013 quello appena ribattezzato \u2013 contro Cobolli. Ma visto che Ga\u00ebl e Andrey erano sul Campo dei Principi, l\u2019idea \u00e9 che gli altri siano sul Rainier III<\/em>&#8220;.<\/p>\n<div id=\"attachment_85887\" style=\"width: 310px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-85887\" class=\"size-medium wp-image-85887\" src=\"https:\/\/montecarlotennismasters.com\/wp-content\/uploads\/2025\/04\/coc-6377-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/montecarlotennismasters.com\/wp-content\/uploads\/2025\/04\/coc-6377-300x200.jpg 300w, https:\/\/montecarlotennismasters.com\/wp-content\/uploads\/2025\/04\/coc-6377-1024x682.jpg 1024w, https:\/\/montecarlotennismasters.com\/wp-content\/uploads\/2025\/04\/coc-6377-768x512.jpg 768w, https:\/\/montecarlotennismasters.com\/wp-content\/uploads\/2025\/04\/coc-6377-1536x1023.jpg 1536w, https:\/\/montecarlotennismasters.com\/wp-content\/uploads\/2025\/04\/coc-6377-2048x1364.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-85887\" class=\"wp-caption-text\">MONTE-CARLO, MONACO- APRIL 9: Images of Andrey Rublev from Russia on day 4,<br \/>photo by Corinne Dubreuil\/ATP Tour<\/p><\/div>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\u00a0Gli amanti dei giochi di parole sono rimasti delusi. Un duello Monfils-Fils avrebbe fatto abbastanza sorridere. Quindi sar\u00e0 Rublev \u2013 Fils. Perch\u00e9 il vincitore dell&#8217;edizione 2023 ha mantenuto la posizione di testa di serie numero 7, non senza un difficile combattimento ontro Monfils. Nonostante Monf si sia dispiaciuto delle occasioni mancate nel primo set (vinto 6-4 da Rublev), nel secondo era in vantaggio 5-3 e ha servito sul 5-4, pareggiando il conto di un set. Poi, in modalit\u00e0 &#8220;terminator&#8221;, ha iniziato a sganciare bombe super potenti, &#8220;Go, go&#8221; gridavano dagli spalti nei momenti salienti del match ove gli spettatori chiedevano dei colpi spettacolari. Anche Grigor Dimitrov, che aspettava il momento del suo incontro contro Vacherot, si \u00e8 affacciato alla finestra della palestra privata dei giocatori per assistere alla fine del secondo set.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">5-4 quindi Monfils serve. 40-15 due set point. La prima palla: doppio fallo (il 2\u00b0 della partita, alla fine saranno 4). \u00a0Seconda palla: servizio di volata sul secondo servizio, dritto inarrestabile di Rublev. Pochi secondi dopo, un altro quasi doppio fallo, e Monfils preoccupato, mostra il suo timore in risposta allo stress del pubblico. Poi il gioco riprende con calma. Invano Rublev vince il tie-break, che domina senza battere ciglio. Fine della partita. &#8220;<em>Tutti parlano di questa partita 5-4 da quando ho lasciato il campo&#8221;, <\/em>ha detto Monfils<em>. Ma \u00e8 stato un insieme di cose. Non sono stato perfetto tutto il tempo, alcuni momenti li ho gestiti male. Avrei dovuto fare le cose diversamente, magari rallentando di tanto in tanto. Mi sento un po&#8217; in colpa per questo<\/em>. \u00bb<\/p>\n<p style=\"text-align: justify;\">Con Gasquet e Monfils eliminati, i due nonni trentottenni lasceranno Monaco. Un ultima parola, Ga\u00ebl, su Richard? Grande sorriso e occhi brillanti\u2026 \u201c<em>Ci vediamo al Roland<\/em>!\u201d Questo tipo non lo \u00a0cambieremo mai.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Il Russo domina il Francese 6-4, 7-6 in 1h45 nonostante per due volte sia arrivato quasi alla vittoria<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-85944","post","type-post","status-publish","format-standard","hentry","category-non-classifiee-it"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rublev riesce a piegare Monfils - Rolex Monte-Carlo Masters<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/montecarlotennismasters.com\/it\/rublev-riesce-a-piegare-monfils\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rublev riesce a piegare Monfils - Rolex Monte-Carlo Masters\" \/>\n<meta property=\"og:description\" content=\"Il Russo domina il Francese 6-4, 7-6 in 1h45 nonostante per due volte sia arrivato quasi alla vittoria\" \/>\n<meta property=\"og:url\" content=\"https:\/\/montecarlotennismasters.com\/it\/rublev-riesce-a-piegare-monfils\/\" \/>\n<meta property=\"og:site_name\" content=\"Rolex Monte-Carlo Masters\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-09T17:03:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/montecarlotennismasters.com\/wp-content\/uploads\/2025\/04\/coc-6377-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1705\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eric SILVESTRO\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eric SILVESTRO\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/rublev-riesce-a-piegare-monfils\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/rublev-riesce-a-piegare-monfils\\\/\"},\"author\":{\"name\":\"Eric SILVESTRO\",\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/#\\\/schema\\\/person\\\/2ba3ea68fef415c502ae40903053fada\"},\"headline\":\"Rublev riesce a piegare Monfils\",\"datePublished\":\"2025-04-09T17:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/rublev-riesce-a-piegare-monfils\\\/\"},\"wordCount\":523,\"image\":{\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/rublev-riesce-a-piegare-monfils\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/montecarlotennismasters.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/coc-6377-300x200.jpg\",\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/rublev-riesce-a-piegare-monfils\\\/\",\"url\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/rublev-riesce-a-piegare-monfils\\\/\",\"name\":\"Rublev riesce a piegare Monfils - Rolex Monte-Carlo Masters\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/rublev-riesce-a-piegare-monfils\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/rublev-riesce-a-piegare-monfils\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/montecarlotennismasters.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/coc-6377-300x200.jpg\",\"datePublished\":\"2025-04-09T17:03:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/#\\\/schema\\\/person\\\/2ba3ea68fef415c502ae40903053fada\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/rublev-riesce-a-piegare-monfils\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/rublev-riesce-a-piegare-monfils\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/rublev-riesce-a-piegare-monfils\\\/#primaryimage\",\"url\":\"https:\\\/\\\/montecarlotennismasters.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/coc-6377-300x200.jpg\",\"contentUrl\":\"https:\\\/\\\/montecarlotennismasters.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/coc-6377-300x200.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/rublev-riesce-a-piegare-monfils\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rublev riesce a piegare Monfils\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/#website\",\"url\":\"https:\\\/\\\/montecarlotennismasters.com\\\/\",\"name\":\"Rolex Monte-Carlo Masters\",\"description\":\"11-19 aprile 2020\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/montecarlotennismasters.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/#\\\/schema\\\/person\\\/2ba3ea68fef415c502ae40903053fada\",\"name\":\"Eric SILVESTRO\",\"url\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/author\\\/esilvestro\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rublev riesce a piegare Monfils - Rolex Monte-Carlo Masters","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/montecarlotennismasters.com\/it\/rublev-riesce-a-piegare-monfils\/","og_locale":"it_IT","og_type":"article","og_title":"Rublev riesce a piegare Monfils - Rolex Monte-Carlo Masters","og_description":"Il Russo domina il Francese 6-4, 7-6 in 1h45 nonostante per due volte sia arrivato quasi alla vittoria","og_url":"https:\/\/montecarlotennismasters.com\/it\/rublev-riesce-a-piegare-monfils\/","og_site_name":"Rolex Monte-Carlo Masters","article_published_time":"2025-04-09T17:03:39+00:00","og_image":[{"width":2560,"height":1705,"url":"https:\/\/montecarlotennismasters.com\/wp-content\/uploads\/2025\/04\/coc-6377-scaled.jpg","type":"image\/jpeg"}],"author":"Eric SILVESTRO","twitter_misc":{"Scritto da":"Eric SILVESTRO","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/montecarlotennismasters.com\/it\/rublev-riesce-a-piegare-monfils\/#article","isPartOf":{"@id":"https:\/\/montecarlotennismasters.com\/it\/rublev-riesce-a-piegare-monfils\/"},"author":{"name":"Eric SILVESTRO","@id":"https:\/\/montecarlotennismasters.com\/#\/schema\/person\/2ba3ea68fef415c502ae40903053fada"},"headline":"Rublev riesce a piegare Monfils","datePublished":"2025-04-09T17:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/montecarlotennismasters.com\/it\/rublev-riesce-a-piegare-monfils\/"},"wordCount":523,"image":{"@id":"https:\/\/montecarlotennismasters.com\/it\/rublev-riesce-a-piegare-monfils\/#primaryimage"},"thumbnailUrl":"https:\/\/montecarlotennismasters.com\/wp-content\/uploads\/2025\/04\/coc-6377-300x200.jpg","articleSection":["Non classifi\u00e9(e)"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/montecarlotennismasters.com\/it\/rublev-riesce-a-piegare-monfils\/","url":"https:\/\/montecarlotennismasters.com\/it\/rublev-riesce-a-piegare-monfils\/","name":"Rublev riesce a piegare Monfils - Rolex Monte-Carlo Masters","isPartOf":{"@id":"https:\/\/montecarlotennismasters.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/montecarlotennismasters.com\/it\/rublev-riesce-a-piegare-monfils\/#primaryimage"},"image":{"@id":"https:\/\/montecarlotennismasters.com\/it\/rublev-riesce-a-piegare-monfils\/#primaryimage"},"thumbnailUrl":"https:\/\/montecarlotennismasters.com\/wp-content\/uploads\/2025\/04\/coc-6377-300x200.jpg","datePublished":"2025-04-09T17:03:39+00:00","author":{"@id":"https:\/\/montecarlotennismasters.com\/#\/schema\/person\/2ba3ea68fef415c502ae40903053fada"},"breadcrumb":{"@id":"https:\/\/montecarlotennismasters.com\/it\/rublev-riesce-a-piegare-monfils\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/montecarlotennismasters.com\/it\/rublev-riesce-a-piegare-monfils\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/montecarlotennismasters.com\/it\/rublev-riesce-a-piegare-monfils\/#primaryimage","url":"https:\/\/montecarlotennismasters.com\/wp-content\/uploads\/2025\/04\/coc-6377-300x200.jpg","contentUrl":"https:\/\/montecarlotennismasters.com\/wp-content\/uploads\/2025\/04\/coc-6377-300x200.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/montecarlotennismasters.com\/it\/rublev-riesce-a-piegare-monfils\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/montecarlotennismasters.com\/it\/"},{"@type":"ListItem","position":2,"name":"Rublev riesce a piegare Monfils"}]},{"@type":"WebSite","@id":"https:\/\/montecarlotennismasters.com\/#website","url":"https:\/\/montecarlotennismasters.com\/","name":"Rolex Monte-Carlo Masters","description":"11-19 aprile 2020","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/montecarlotennismasters.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/montecarlotennismasters.com\/#\/schema\/person\/2ba3ea68fef415c502ae40903053fada","name":"Eric SILVESTRO","url":"https:\/\/montecarlotennismasters.com\/it\/author\/esilvestro\/"}]}},"_links":{"self":[{"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/posts\/85944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/comments?post=85944"}],"version-history":[{"count":0,"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/posts\/85944\/revisions"}],"wp:attachment":[{"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/media?parent=85944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/categories?post=85944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/tags?post=85944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}