{"id":86298,"date":"2025-04-11T13:06:58","date_gmt":"2025-04-11T11:06:58","guid":{"rendered":"https:\/\/montecarlotennismasters.com\/?p=86298"},"modified":"2025-04-11T13:08:05","modified_gmt":"2025-04-11T11:08:05","slug":"86298","status":"publish","type":"post","link":"https:\/\/montecarlotennismasters.com\/it\/86298\/","title":{"rendered":"Davidovich Fokina qualificato  per le finali"},"content":{"rendered":"<p style=\"text-align: justify;\">Senza tremare, Alejandro Davidovich Fokina ha mantenuto fede alla sua reputazione di aficionado della terra rossa. Venerd\u00ec 11 aprile ha dominato il dibattito contro Alexei Popyrin. Gli ci sono voluti solo 1 ora e 9 minuti per vincere 6-3 6-2 e qualificarsi cos\u00ec per le semifinali.<\/p>\n<p style=\"text-align: justify;\">Sulla carta la partita sembrava equilibrata. Da una parte, Alejandro Davidovich Fokina, incostante nel gioco regolare ma formidabile sulla terra battuta, finalista del Rolex Monte-Carlo Masters nel 2021. dall&#8217;altra, Alexei Popyrin, felice outsider di questa 118a edizione e capace di brillare nei match importanti. Il giorno prima, il numero 27 del mondo aveva eliminato Casper Ruud, testa di serie numero 4, serio contendente al titolo, finalista lo scorso anno a Monaco, due volte finalista al Roland Garros nel 2022 e nel 2023.<\/p>\n<div id=\"attachment_86275\" style=\"width: 310px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-86275\" class=\"size-medium wp-image-86275\" src=\"https:\/\/montecarlotennismasters.com\/wp-content\/uploads\/2025\/04\/davidovich-3716-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/montecarlotennismasters.com\/wp-content\/uploads\/2025\/04\/davidovich-3716-300x200.jpg 300w, https:\/\/montecarlotennismasters.com\/wp-content\/uploads\/2025\/04\/davidovich-3716-1024x683.jpg 1024w, https:\/\/montecarlotennismasters.com\/wp-content\/uploads\/2025\/04\/davidovich-3716-768x512.jpg 768w, https:\/\/montecarlotennismasters.com\/wp-content\/uploads\/2025\/04\/davidovich-3716-1536x1024.jpg 1536w, https:\/\/montecarlotennismasters.com\/wp-content\/uploads\/2025\/04\/davidovich-3716-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-86275\" class=\"wp-caption-text\">Tennis : Rolex Monte Carlo Masters 2025 &#8211; Atp &#8211;<\/p><\/div>\n<p style=\"text-align: justify;\">Il primo turno \u00e8 stato piuttosto equilibrato. Lo spagnolo, 42\u00b0 nella classifica ATP, ha fatto la differenza al momento giusto. Fa il break sul 4-3 per portarsi sul 5-3 e aggiudicarsi il set sul 6-3. La seconda parte \u00e8 stata molto pi\u00f9 spedita. Il finalista del 2021 ha subito preso il servizio avversario per portarsi in vantaggio con 4-0. Al contrario, l&#8217;australiano sembra non avere una soluzione e commette una serie di falli diretti. Lancia addirittura una palla tra il pubblico. 5-2, lo spqgnolo, nativo di Malaga serve per un posto in semifinale. E senza paura ci riesce anche. &#8220;<em>Sono contento di aver migliorato il mio livello e il modo in cui ho giocato ogg<\/em>i&#8221;, ha dichiarato il vincitore a bordo campo. Ieri Davidovich Fokina ha avuto una partita strana contro Jack Draper. Mentre era in vantaggio per 1 set -1 break, si \u00e8 lasciato trasportare e alla fine ha dovuto impegnarsi molto nel terzo set per vincere. &#8220;<em>Ieri ho parlato a lungo con la mia squadra, ho detto loro che non volevo continuare cos\u00ec per il resto della mia carriera. Oggi sono contento perch\u00e9 sono riuscito a rimanere concentrato, devo riuscire a cambiare mentalmente&#8221;<\/em>, ha sottolineato.<\/p>\n<p>Gi\u00e0 due finali nel 2025 per lo spagnolo, una a Delray Beach e un&#8217;altra ad Acapulco. Per riprovare ad importsi sulla terra Monegasca, dovr\u00e0 affrontare il vincitore dell&#8217;attesissimo scontro tra Arthur Fils e Carlos Alcaraz. &#8220;<em>Non ho preferenze tra i due, spero solo che la partita duri abbastanza in modo da stancarli un po&#8221;<\/em>, dichiara scherzandoci sopra. &#8220;<em>In ogni caso, ci prover\u00f2 gusto<\/em>.&#8221;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo Spagnolo si qualifica in semi finale senza troppi sforzi, battendo Alexei Popyrin 6-3, 6-2<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-86298","post","type-post","status-publish","format-standard","hentry","category-non-classifiee-it"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Davidovich Fokina qualificato per le finali - Rolex Monte-Carlo Masters<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/montecarlotennismasters.com\/it\/86298\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Davidovich Fokina qualificato per le finali - Rolex Monte-Carlo Masters\" \/>\n<meta property=\"og:description\" content=\"Lo Spagnolo si qualifica in semi finale senza troppi sforzi, battendo Alexei Popyrin 6-3, 6-2\" \/>\n<meta property=\"og:url\" content=\"https:\/\/montecarlotennismasters.com\/it\/86298\/\" \/>\n<meta property=\"og:site_name\" content=\"Rolex Monte-Carlo Masters\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-11T11:06:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-11T11:08:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/montecarlotennismasters.com\/wp-content\/uploads\/2025\/04\/davidovich-3716-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eric SILVESTRO\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eric SILVESTRO\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/86298\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/86298\\\/\"},\"author\":{\"name\":\"Eric SILVESTRO\",\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/#\\\/schema\\\/person\\\/2ba3ea68fef415c502ae40903053fada\"},\"headline\":\"Davidovich Fokina qualificato per le finali\",\"datePublished\":\"2025-04-11T11:06:58+00:00\",\"dateModified\":\"2025-04-11T11:08:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/86298\\\/\"},\"wordCount\":399,\"image\":{\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/86298\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/montecarlotennismasters.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/davidovich-3716-300x200.jpg\",\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/86298\\\/\",\"url\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/86298\\\/\",\"name\":\"Davidovich Fokina qualificato per le finali - Rolex Monte-Carlo Masters\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/86298\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/86298\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/montecarlotennismasters.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/davidovich-3716-300x200.jpg\",\"datePublished\":\"2025-04-11T11:06:58+00:00\",\"dateModified\":\"2025-04-11T11:08:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/#\\\/schema\\\/person\\\/2ba3ea68fef415c502ae40903053fada\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/86298\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/86298\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/86298\\\/#primaryimage\",\"url\":\"https:\\\/\\\/montecarlotennismasters.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/davidovich-3716-300x200.jpg\",\"contentUrl\":\"https:\\\/\\\/montecarlotennismasters.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/davidovich-3716-300x200.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/86298\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Davidovich Fokina qualificato per le finali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/#website\",\"url\":\"https:\\\/\\\/montecarlotennismasters.com\\\/\",\"name\":\"Rolex Monte-Carlo Masters\",\"description\":\"11-19 aprile 2020\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/montecarlotennismasters.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/#\\\/schema\\\/person\\\/2ba3ea68fef415c502ae40903053fada\",\"name\":\"Eric SILVESTRO\",\"url\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/author\\\/esilvestro\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Davidovich Fokina qualificato per le finali - Rolex Monte-Carlo Masters","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/montecarlotennismasters.com\/it\/86298\/","og_locale":"it_IT","og_type":"article","og_title":"Davidovich Fokina qualificato per le finali - Rolex Monte-Carlo Masters","og_description":"Lo Spagnolo si qualifica in semi finale senza troppi sforzi, battendo Alexei Popyrin 6-3, 6-2","og_url":"https:\/\/montecarlotennismasters.com\/it\/86298\/","og_site_name":"Rolex Monte-Carlo Masters","article_published_time":"2025-04-11T11:06:58+00:00","article_modified_time":"2025-04-11T11:08:05+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/montecarlotennismasters.com\/wp-content\/uploads\/2025\/04\/davidovich-3716-scaled.jpg","type":"image\/jpeg"}],"author":"Eric SILVESTRO","twitter_misc":{"Scritto da":"Eric SILVESTRO","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/montecarlotennismasters.com\/it\/86298\/#article","isPartOf":{"@id":"https:\/\/montecarlotennismasters.com\/it\/86298\/"},"author":{"name":"Eric SILVESTRO","@id":"https:\/\/montecarlotennismasters.com\/#\/schema\/person\/2ba3ea68fef415c502ae40903053fada"},"headline":"Davidovich Fokina qualificato per le finali","datePublished":"2025-04-11T11:06:58+00:00","dateModified":"2025-04-11T11:08:05+00:00","mainEntityOfPage":{"@id":"https:\/\/montecarlotennismasters.com\/it\/86298\/"},"wordCount":399,"image":{"@id":"https:\/\/montecarlotennismasters.com\/it\/86298\/#primaryimage"},"thumbnailUrl":"https:\/\/montecarlotennismasters.com\/wp-content\/uploads\/2025\/04\/davidovich-3716-300x200.jpg","articleSection":["Non classifi\u00e9(e)"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/montecarlotennismasters.com\/it\/86298\/","url":"https:\/\/montecarlotennismasters.com\/it\/86298\/","name":"Davidovich Fokina qualificato per le finali - Rolex Monte-Carlo Masters","isPartOf":{"@id":"https:\/\/montecarlotennismasters.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/montecarlotennismasters.com\/it\/86298\/#primaryimage"},"image":{"@id":"https:\/\/montecarlotennismasters.com\/it\/86298\/#primaryimage"},"thumbnailUrl":"https:\/\/montecarlotennismasters.com\/wp-content\/uploads\/2025\/04\/davidovich-3716-300x200.jpg","datePublished":"2025-04-11T11:06:58+00:00","dateModified":"2025-04-11T11:08:05+00:00","author":{"@id":"https:\/\/montecarlotennismasters.com\/#\/schema\/person\/2ba3ea68fef415c502ae40903053fada"},"breadcrumb":{"@id":"https:\/\/montecarlotennismasters.com\/it\/86298\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/montecarlotennismasters.com\/it\/86298\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/montecarlotennismasters.com\/it\/86298\/#primaryimage","url":"https:\/\/montecarlotennismasters.com\/wp-content\/uploads\/2025\/04\/davidovich-3716-300x200.jpg","contentUrl":"https:\/\/montecarlotennismasters.com\/wp-content\/uploads\/2025\/04\/davidovich-3716-300x200.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/montecarlotennismasters.com\/it\/86298\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/montecarlotennismasters.com\/it\/"},{"@type":"ListItem","position":2,"name":"Davidovich Fokina qualificato per le finali"}]},{"@type":"WebSite","@id":"https:\/\/montecarlotennismasters.com\/#website","url":"https:\/\/montecarlotennismasters.com\/","name":"Rolex Monte-Carlo Masters","description":"11-19 aprile 2020","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/montecarlotennismasters.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/montecarlotennismasters.com\/#\/schema\/person\/2ba3ea68fef415c502ae40903053fada","name":"Eric SILVESTRO","url":"https:\/\/montecarlotennismasters.com\/it\/author\/esilvestro\/"}]}},"_links":{"self":[{"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/posts\/86298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/comments?post=86298"}],"version-history":[{"count":0,"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/posts\/86298\/revisions"}],"wp:attachment":[{"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/media?parent=86298"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/categories?post=86298"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/tags?post=86298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}