{"id":86558,"date":"2025-04-12T15:26:13","date_gmt":"2025-04-12T13:26:13","guid":{"rendered":"https:\/\/montecarlotennismasters.com\/?p=86558"},"modified":"2025-04-13T09:44:44","modified_gmt":"2025-04-13T07:44:44","slug":"un-po-per-tutti-i-gusti","status":"publish","type":"post","link":"https:\/\/montecarlotennismasters.com\/it\/un-po-per-tutti-i-gusti\/","title":{"rendered":"Un po&#8217; per tutti i gusti"},"content":{"rendered":"<p style=\"text-align: justify;\">Un ex finalista (Davidovich Fokina), il campione del Roland-Garros (Alcaraz), il beniamino degli spalti (Musetti) e un ospite non proprio a sorpresa (de Minaur): le semifinali della 118a edizione del Rolex Monte-Carlo Masters si preannunciano tanto emozionanti quanto incerte. Ecco la presentazione dei concorrenti.<\/p>\n<p style=\"text-align: justify;\"><strong>Carlos Alcaraz \u2013 Alejandro Davidovich Fokina<\/strong><\/p>\n<p style=\"text-align: justify;\">Carlos Alcaraz ha dovuto aspettare un po&#8217;, prima di vincere finalmente i suoi primi incontri al Rolex Monte-Carlo Masters. Nel 2022, reduce dal titolo al Miami Masters 1000, arriva nel Principato esausto, senza preparazione sulla terra battuta e perde al primo incontro, nonostante una dura lotta, contro Sebastian Korda. L&#8217;anno scorso, a causa di un dolore lancinante all&#8217;avambraccio, deve ritirarsi all&#8217;ultimo minuto. E purtroppo perde all&#8217;inizio di questa settimana, il primo set per 6-3 contro Cerundolo. Viene rapidamente spazzato via dallo spagnolo per 6-0, 6-1. E se Altmaier non ha opposto molta resistenza, il suo quarto di finale contro Fils \u00e8 stato molto pi\u00f9 indeciso. Ecco quindi il detentore del titolo del Roland-Garros, giunto alle semifinali, con un unico obiettivo: vincere il suo primo &#8220;Monte-Carlo&#8221; esattamente 20 anni dopo il primo degli 11 titoli di&#8230; Rafael Nadal!<\/p>\n<p style=\"text-align: justify;\">Per riuscirci, Alcaraz dovr\u00e0 prima sconfiggere il suo connazionale Alejandro Davidovich Fokina, in una semifinale tutta spagnola, una prima volta dal 2010, quando Nadal aveva eliminato Ferrer quell&#8217;anno e stravinto contro Verdasco in finale. Una finale che Davidovich Fokina ha gi\u00e0 giocato al Rolex Monte-Carlo Masters, nel 2022, contro Stefanos Tsitsipas. All&#8217;epoca numero 46 del mondo, fa scalpore eliminando Giron, Djokovic, Goffin, Fritz e Dimitrov per poi salire al 27\u00b0 posto della classifica ATP in una sola settimana. Sfortunatamente per lui, poi ha avuto difficolt\u00e0 a confermare la vittoria. Prima di riprendere fiato quest&#8217;anno con due nuove finali, a Delray Beach (battuto da Kecmanovic) e ad Acapulco (battuto da Machac). Attenzione per\u00f2 alla stanchezza nelle prime tre partite di questa settimana, e ad un quarto di finale piuttosto tranquillo contro Popyrin.<\/p>\n<p style=\"text-align: justify;\"><strong>Il Testa a testa<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0<strong>Alcaraz-Davidovich Fokina: 1-0<\/strong><\/p>\n<p style=\"text-align: justify;\">2023, Barcellona, \u200b\u200bterra battuta, quarti di finale, Alcaraz 7-6(5), 6-3<\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0I rispettivi percorsi \u00a0<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0Carlos Alcaraz<\/strong><\/p>\n<p style=\"text-align: justify;\">1\u00b0 turno: ritirato<\/p>\n<p style=\"text-align: justify;\">2\u00b0 turno: batte Francisco Cerundolo (ARG) 3-6, 6-0, 6-1<\/p>\n<p style=\"text-align: justify;\">1\/8 di finale: batte Daniel Altmaier (ALL) 6-3, 6-1<\/p>\n<p style=\"text-align: justify;\">Quarti di finale: batte Arthur Fils (FRA) 4-6, 7-5, 6-3<\/p>\n<p style=\"text-align: justify;\"><strong>Alejandro Davidovich Fokina<\/strong><\/p>\n<p style=\"text-align: justify;\">1\u00b0 turno\u00a0: batte Ben Shelton (USA) 6-7(2), 6-2, 6-1<\/p>\n<p style=\"text-align: justify;\">2\u00b0 turno\u00a0: batte Tomas Martin Etcheverry (ARG) 7-6(2) 6-3<\/p>\n<p style=\"text-align: justify;\">1\/8\u00b0 di finale\u00a0: batte Jack Draper (GBR) 6-3, 6-7(6), 6-4<\/p>\n<p style=\"text-align: justify;\">Quarti di finale\u00a0: batte Alexei Popyrin (AUS) 6-3, 6-2<\/p>\n<p style=\"text-align: justify;\">***<\/p>\n<p style=\"text-align: justify;\"><strong>Alex de Minaur-Lorenzo Musetti<\/strong><\/p>\n<p style=\"text-align: justify;\">Il percorso di Alex de Minaur al Rolex Monte-Carlo Masters rispecchia la sua carriera nell&#8217;ATP Tour: discreta ma in costante miglioramento. Eliminato due volte al primo turno nel 2018 (Seppi) e<\/p>\n<p style=\"text-align: justify;\">2021 (Davidovich Fokina), \u00e8 poi leggermente migliorato nel 2022 e nel 2023 con un secondo turno (Rublev e Struff) e ancora meglio nel 2024 con un quarto di finale (vittorie contro Wawrinka, Griekspoor e Popyrin \u2013 sconfitta contro Djokovic). Quindi eccolo qui quest&#8217;anno, tra gli ultimi quattro. A parte il primo set perso contro Machac al primo turno, da allora de Minaur ha perso solo quattro game contro Medvedev e nessuno contro Dimitrov. Un &#8220;6-0, 6-0&#8221; in 44 minuti, la prima volta da quando ci era riuscito Alex Corretja contro Nuno Marques nel 1997. Sapendo che solo Ilie Nastase (Goven 1974), Arthur Ashe (Dell 1975) e Guillermo Vilas (Nastase 1981) erano stati cos\u00ec spietati. De Minaur avr\u00e0 quindi il vantaggio di essere giovane e fresco.<\/p>\n<p style=\"text-align: justify;\">Contro di lui, anche Lorenzo Musetti giocher\u00e0 la sua prima semifinale al Rolex Monte-Carlo Masters (e al Masters 1000) dopo aver battuto a sorpresa nei quarti di finale il campione in carica Tsitsipas, complice l&#8217;entusiasmo e il calore del pubblico italiano. E perfino la sua prima semifinale nel circuito da ottobre 2024 a Vienna (battuta da Draper). Quarto di finale nel 2023 (battuto dal connazionale Sinner) dopo aver eliminato Djokovic, Musetti conferma di essere un giocatore di grande precisione nei colpi, con un gioco a tratti davvero incantevole. Nonostante i suoi lunghi capelli castani abbiano lasciato il posto a un taglio corto pi\u00f9 discreto, il ventitreenne italiano \u00e8 tornato a sorridere a Monaco. &#8220;<em>Crediamoci!<\/em>&#8220;, scrive alla telecamera dopo essersi qualificato per le semifinali. Bisogna dire che Musetti \u00e8 un po&#8217; un miracolo: per ben tre volte questa settimana, contro Bu, Lehecka e Tsitispas, ha perso nel primo set pur essendo molto in svantaggio e pronto per lasciare la partita. Attenzione pero a non esser troppo stanco.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Il Testa a testa<\/strong><\/p>\n<p>de Minaur \u2013 Musetti: 1-1<\/p>\n<p>2022, Australian Open, cemento, 1\u00b0 turno, de Minaur 3-6, 6-3, 6-0, 6-3<\/p>\n<p>2024, Queen&#8217;s, erba, 1\u00b0 turno, Musetti 1-6, 6-4, 6-2<\/p>\n<p><strong>I loro percorsi <\/strong><\/p>\n<p><strong>Alex de Minaur<\/strong><\/p>\n<p>1\u00b0 turno: ritirato<\/p>\n<p>2\u00b0 turno: batte Tomas Machac (RTC) 3-6, 6-0, 6-3<\/p>\n<p>Ottavi di finale: batte Danill Medvedev (RUS) 6-2, 6-2<\/p>\n<p>Quarti di finale: sconfigge Grigor Dimitrov (BUL) 6-0, 6-0<\/p>\n<p><strong>Lorenzo Musetti <\/strong><\/p>\n<p>1\u00b0 turno: sconfigge Yunchaokete Bu (CHN) 4-6, 7-5, 6-3<\/p>\n<p>2\u00b0 turno: batte Jiri Lehecka (RTC) 1-6, 7-5, 6-2<\/p>\n<p>Ottavi di finale: batte Matteo Berrettini (ITA) 6-3, 6-3<\/p>\n<p>Quarti di finale: batte Stefanos Tsitsipas 1-6, 6-3, 6-4<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alcaraz &#8211; Davidovich Fokina e de Minaur &#8211; Musetti: quattro pretendenti per due posti in finale<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-86558","post","type-post","status-publish","format-standard","hentry","category-non-classifiee-it"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un po&#039; per tutti i gusti - Rolex Monte-Carlo Masters<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/montecarlotennismasters.com\/it\/un-po-per-tutti-i-gusti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un po&#039; per tutti i gusti - Rolex Monte-Carlo Masters\" \/>\n<meta property=\"og:description\" content=\"Alcaraz - Davidovich Fokina e de Minaur - Musetti: quattro pretendenti per due posti in finale\" \/>\n<meta property=\"og:url\" content=\"https:\/\/montecarlotennismasters.com\/it\/un-po-per-tutti-i-gusti\/\" \/>\n<meta property=\"og:site_name\" content=\"Rolex Monte-Carlo Masters\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-12T13:26:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-13T07:44:44+00:00\" \/>\n<meta name=\"author\" content=\"Eric SILVESTRO\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eric SILVESTRO\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/un-po-per-tutti-i-gusti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/un-po-per-tutti-i-gusti\\\/\"},\"author\":{\"name\":\"Eric SILVESTRO\",\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/#\\\/schema\\\/person\\\/2ba3ea68fef415c502ae40903053fada\"},\"headline\":\"Un po&#8217; per tutti i gusti\",\"datePublished\":\"2025-04-12T13:26:13+00:00\",\"dateModified\":\"2025-04-13T07:44:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/un-po-per-tutti-i-gusti\\\/\"},\"wordCount\":816,\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/un-po-per-tutti-i-gusti\\\/\",\"url\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/un-po-per-tutti-i-gusti\\\/\",\"name\":\"Un po' per tutti i gusti - Rolex Monte-Carlo Masters\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/#website\"},\"datePublished\":\"2025-04-12T13:26:13+00:00\",\"dateModified\":\"2025-04-13T07:44:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/#\\\/schema\\\/person\\\/2ba3ea68fef415c502ae40903053fada\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/un-po-per-tutti-i-gusti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/un-po-per-tutti-i-gusti\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/un-po-per-tutti-i-gusti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un po&rsquo; per tutti i gusti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/#website\",\"url\":\"https:\\\/\\\/montecarlotennismasters.com\\\/\",\"name\":\"Rolex Monte-Carlo Masters\",\"description\":\"11-19 aprile 2020\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/montecarlotennismasters.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/#\\\/schema\\\/person\\\/2ba3ea68fef415c502ae40903053fada\",\"name\":\"Eric SILVESTRO\",\"url\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/author\\\/esilvestro\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un po' per tutti i gusti - Rolex Monte-Carlo Masters","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/montecarlotennismasters.com\/it\/un-po-per-tutti-i-gusti\/","og_locale":"it_IT","og_type":"article","og_title":"Un po' per tutti i gusti - Rolex Monte-Carlo Masters","og_description":"Alcaraz - Davidovich Fokina e de Minaur - Musetti: quattro pretendenti per due posti in finale","og_url":"https:\/\/montecarlotennismasters.com\/it\/un-po-per-tutti-i-gusti\/","og_site_name":"Rolex Monte-Carlo Masters","article_published_time":"2025-04-12T13:26:13+00:00","article_modified_time":"2025-04-13T07:44:44+00:00","author":"Eric SILVESTRO","twitter_misc":{"Scritto da":"Eric SILVESTRO","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/montecarlotennismasters.com\/it\/un-po-per-tutti-i-gusti\/#article","isPartOf":{"@id":"https:\/\/montecarlotennismasters.com\/it\/un-po-per-tutti-i-gusti\/"},"author":{"name":"Eric SILVESTRO","@id":"https:\/\/montecarlotennismasters.com\/#\/schema\/person\/2ba3ea68fef415c502ae40903053fada"},"headline":"Un po&#8217; per tutti i gusti","datePublished":"2025-04-12T13:26:13+00:00","dateModified":"2025-04-13T07:44:44+00:00","mainEntityOfPage":{"@id":"https:\/\/montecarlotennismasters.com\/it\/un-po-per-tutti-i-gusti\/"},"wordCount":816,"articleSection":["Non classifi\u00e9(e)"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/montecarlotennismasters.com\/it\/un-po-per-tutti-i-gusti\/","url":"https:\/\/montecarlotennismasters.com\/it\/un-po-per-tutti-i-gusti\/","name":"Un po' per tutti i gusti - Rolex Monte-Carlo Masters","isPartOf":{"@id":"https:\/\/montecarlotennismasters.com\/#website"},"datePublished":"2025-04-12T13:26:13+00:00","dateModified":"2025-04-13T07:44:44+00:00","author":{"@id":"https:\/\/montecarlotennismasters.com\/#\/schema\/person\/2ba3ea68fef415c502ae40903053fada"},"breadcrumb":{"@id":"https:\/\/montecarlotennismasters.com\/it\/un-po-per-tutti-i-gusti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/montecarlotennismasters.com\/it\/un-po-per-tutti-i-gusti\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/montecarlotennismasters.com\/it\/un-po-per-tutti-i-gusti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/montecarlotennismasters.com\/it\/"},{"@type":"ListItem","position":2,"name":"Un po&rsquo; per tutti i gusti"}]},{"@type":"WebSite","@id":"https:\/\/montecarlotennismasters.com\/#website","url":"https:\/\/montecarlotennismasters.com\/","name":"Rolex Monte-Carlo Masters","description":"11-19 aprile 2020","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/montecarlotennismasters.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/montecarlotennismasters.com\/#\/schema\/person\/2ba3ea68fef415c502ae40903053fada","name":"Eric SILVESTRO","url":"https:\/\/montecarlotennismasters.com\/it\/author\/esilvestro\/"}]}},"_links":{"self":[{"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/posts\/86558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/comments?post=86558"}],"version-history":[{"count":0,"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/posts\/86558\/revisions"}],"wp:attachment":[{"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/media?parent=86558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/categories?post=86558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/tags?post=86558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}