{"id":86720,"date":"2025-04-13T13:55:25","date_gmt":"2025-04-13T11:55:25","guid":{"rendered":"https:\/\/montecarlotennismasters.com\/?p=86720"},"modified":"2025-06-04T15:38:10","modified_gmt":"2025-06-04T13:38:10","slug":"record-di-presenze-e-novita-introdotte","status":"publish","type":"post","link":"https:\/\/montecarlotennismasters.com\/it\/record-di-presenze-e-novita-introdotte\/","title":{"rendered":"Record di presenze e novit\u00e0 introdotte"},"content":{"rendered":"<p style=\"text-align: justify;\">Il <strong>Rolex Monte Carlo Masters 2025<\/strong> \u00e8 stato un successo sotto tutti gli aspetti. Durante la sua tradizionale conferenza stampa di presentazione di questa 118a edizione, David Massey, direttore del torneo, ha salutato con favore un nuovo record di partecipazione: &#8220;<em>Abbiamo quasi raggiunto la capienza massima per questo torneo. L&#8217;anno scorso abbiamo accolto oltre 148.000 persone e quest&#8217;anno supereremo il traguardo storico di 150.000 spettatori nei nove giorni del torneo<\/em>&#8220;.<\/p>\n<p style=\"text-align: justify;\">David Massey ha sottolineato anche il successo delle novit\u00e0 introdotte quest&#8217;anno. <em>\u00ab Una delle \u00a0principali innovazioni del nostro evento quest&#8217;anno \u00e8 stata l&#8217;ampliamento della nostra sede di oltre \u00a035% con l&#8217;introduzione del &#8220;Players Village&#8221;, che ha visto la privatizzazione del Monte-Carlo Beach Club. Credo di aver creato il miglior Player Village al mondo nel campo dei tornei di tennis. Abbiamo ricevuto feedback estremamente positivi dai giocatori. Si tratta di un&#8217;evoluzione importante perch\u00e9 ci mancavano davvero metri quadri dedicati ai giocatori e siamo riusciti a colmare questa lacuna<\/em>.<em> \u00bb<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-87522 size-large\" src=\"https:\/\/montecarlotennismasters.com\/wp-content\/uploads\/2025\/04\/playersvill-1024x681.jpg\" alt=\"\" width=\"1024\" height=\"681\" srcset=\"https:\/\/montecarlotennismasters.com\/wp-content\/uploads\/2025\/04\/playersvill-1024x681.jpg 1024w, https:\/\/montecarlotennismasters.com\/wp-content\/uploads\/2025\/04\/playersvill-300x200.jpg 300w, https:\/\/montecarlotennismasters.com\/wp-content\/uploads\/2025\/04\/playersvill-768x511.jpg 768w, https:\/\/montecarlotennismasters.com\/wp-content\/uploads\/2025\/04\/playersvill-1536x1022.jpg 1536w, https:\/\/montecarlotennismasters.com\/wp-content\/uploads\/2025\/04\/playersvill-2048x1363.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p style=\"text-align: justify;\">Un&#8217;altra innovazione molto importante introdotta dall&#8217;ATP \u00e8 stata il controllo linee digitale. &#8220;<em>Un sistema introdotto quest&#8217;anno in tutti i tornei, ma siamo stati i primi Masters 1000 su terra battuta ad avere il sistema di arbitraggio elettronico. L&#8217;implementazione \u00e8 stata realizzata in collaborazione con l&#8217;azienda Hawk-Ey<\/em>e&#8221;, ha affermato David Massey.<\/p>\n<p style=\"text-align: justify;\"><em>\u00ab Infine, come ben sapete, abbiamo ribattezzato il Campo n. 2 &#8220;Elizabeth-Ann de Massy Courtyard&#8221; per onorare la sua memoria. La Baronessa Elizabeth-Ann de Massy ha svolto un ruolo fondamentale in questo torneo per 50 anni. Siamo entusiasti di aver avuto l&#8217;opportunit\u00e0 \u00a0in qualche modo di onorare la sua memoria nelle partite che abbiamo trasmesso ogni giorno da questo campo. Tutto \u00e8 iniziato con una cerimonia alla quale hanno partecipato tutti i migliori giocatori, oltre a S.A.S. il Principe Alberto II in persona. Questo ci ha anche permesso di vendere i biglietti singolarmente. &#8220;Quindi, per la prima volta, chiunque entrasse nello stadio ha potuto beneficiare di un posto assegnato&#8221;, <\/em>ha aggiunto il direttore del Rolex Monte-Carlo Masters.<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>David Massey, direttore del Rolex Monte-Carlo Masters, fa il bilancio di questa 118a edizione. <\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-86720","post","type-post","status-publish","format-standard","hentry","category-non-classifiee-it"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Record di presenze e novit\u00e0 introdotte - Rolex Monte-Carlo Masters<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/montecarlotennismasters.com\/it\/record-di-presenze-e-novita-introdotte\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Record di presenze e novit\u00e0 introdotte - Rolex Monte-Carlo Masters\" \/>\n<meta property=\"og:description\" content=\"David Massey, direttore del Rolex Monte-Carlo Masters, fa il bilancio di questa 118a edizione.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/montecarlotennismasters.com\/it\/record-di-presenze-e-novita-introdotte\/\" \/>\n<meta property=\"og:site_name\" content=\"Rolex Monte-Carlo Masters\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-13T11:55:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-04T13:38:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/montecarlotennismasters.com\/wp-content\/uploads\/2025\/04\/playersvill-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1703\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eric SILVESTRO\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eric SILVESTRO\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/record-di-presenze-e-novita-introdotte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/record-di-presenze-e-novita-introdotte\\\/\"},\"author\":{\"name\":\"Eric SILVESTRO\",\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/#\\\/schema\\\/person\\\/2ba3ea68fef415c502ae40903053fada\"},\"headline\":\"Record di presenze e novit\u00e0 introdotte\",\"datePublished\":\"2025-04-13T11:55:25+00:00\",\"dateModified\":\"2025-06-04T13:38:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/record-di-presenze-e-novita-introdotte\\\/\"},\"wordCount\":331,\"image\":{\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/record-di-presenze-e-novita-introdotte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/montecarlotennismasters.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/playersvill-1024x681.jpg\",\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/record-di-presenze-e-novita-introdotte\\\/\",\"url\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/record-di-presenze-e-novita-introdotte\\\/\",\"name\":\"Record di presenze e novit\u00e0 introdotte - Rolex Monte-Carlo Masters\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/record-di-presenze-e-novita-introdotte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/record-di-presenze-e-novita-introdotte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/montecarlotennismasters.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/playersvill-1024x681.jpg\",\"datePublished\":\"2025-04-13T11:55:25+00:00\",\"dateModified\":\"2025-06-04T13:38:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/#\\\/schema\\\/person\\\/2ba3ea68fef415c502ae40903053fada\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/record-di-presenze-e-novita-introdotte\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/record-di-presenze-e-novita-introdotte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/record-di-presenze-e-novita-introdotte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/montecarlotennismasters.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/playersvill-1024x681.jpg\",\"contentUrl\":\"https:\\\/\\\/montecarlotennismasters.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/playersvill-1024x681.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/record-di-presenze-e-novita-introdotte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Record di presenze e novit\u00e0 introdotte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/#website\",\"url\":\"https:\\\/\\\/montecarlotennismasters.com\\\/\",\"name\":\"Rolex Monte-Carlo Masters\",\"description\":\"11-19 aprile 2020\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/montecarlotennismasters.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/montecarlotennismasters.com\\\/#\\\/schema\\\/person\\\/2ba3ea68fef415c502ae40903053fada\",\"name\":\"Eric SILVESTRO\",\"url\":\"https:\\\/\\\/montecarlotennismasters.com\\\/it\\\/author\\\/esilvestro\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Record di presenze e novit\u00e0 introdotte - Rolex Monte-Carlo Masters","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/montecarlotennismasters.com\/it\/record-di-presenze-e-novita-introdotte\/","og_locale":"it_IT","og_type":"article","og_title":"Record di presenze e novit\u00e0 introdotte - Rolex Monte-Carlo Masters","og_description":"David Massey, direttore del Rolex Monte-Carlo Masters, fa il bilancio di questa 118a edizione.","og_url":"https:\/\/montecarlotennismasters.com\/it\/record-di-presenze-e-novita-introdotte\/","og_site_name":"Rolex Monte-Carlo Masters","article_published_time":"2025-04-13T11:55:25+00:00","article_modified_time":"2025-06-04T13:38:10+00:00","og_image":[{"width":2560,"height":1703,"url":"https:\/\/montecarlotennismasters.com\/wp-content\/uploads\/2025\/04\/playersvill-scaled.jpg","type":"image\/jpeg"}],"author":"Eric SILVESTRO","twitter_misc":{"Scritto da":"Eric SILVESTRO","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/montecarlotennismasters.com\/it\/record-di-presenze-e-novita-introdotte\/#article","isPartOf":{"@id":"https:\/\/montecarlotennismasters.com\/it\/record-di-presenze-e-novita-introdotte\/"},"author":{"name":"Eric SILVESTRO","@id":"https:\/\/montecarlotennismasters.com\/#\/schema\/person\/2ba3ea68fef415c502ae40903053fada"},"headline":"Record di presenze e novit\u00e0 introdotte","datePublished":"2025-04-13T11:55:25+00:00","dateModified":"2025-06-04T13:38:10+00:00","mainEntityOfPage":{"@id":"https:\/\/montecarlotennismasters.com\/it\/record-di-presenze-e-novita-introdotte\/"},"wordCount":331,"image":{"@id":"https:\/\/montecarlotennismasters.com\/it\/record-di-presenze-e-novita-introdotte\/#primaryimage"},"thumbnailUrl":"https:\/\/montecarlotennismasters.com\/wp-content\/uploads\/2025\/04\/playersvill-1024x681.jpg","articleSection":["Non classifi\u00e9(e)"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/montecarlotennismasters.com\/it\/record-di-presenze-e-novita-introdotte\/","url":"https:\/\/montecarlotennismasters.com\/it\/record-di-presenze-e-novita-introdotte\/","name":"Record di presenze e novit\u00e0 introdotte - Rolex Monte-Carlo Masters","isPartOf":{"@id":"https:\/\/montecarlotennismasters.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/montecarlotennismasters.com\/it\/record-di-presenze-e-novita-introdotte\/#primaryimage"},"image":{"@id":"https:\/\/montecarlotennismasters.com\/it\/record-di-presenze-e-novita-introdotte\/#primaryimage"},"thumbnailUrl":"https:\/\/montecarlotennismasters.com\/wp-content\/uploads\/2025\/04\/playersvill-1024x681.jpg","datePublished":"2025-04-13T11:55:25+00:00","dateModified":"2025-06-04T13:38:10+00:00","author":{"@id":"https:\/\/montecarlotennismasters.com\/#\/schema\/person\/2ba3ea68fef415c502ae40903053fada"},"breadcrumb":{"@id":"https:\/\/montecarlotennismasters.com\/it\/record-di-presenze-e-novita-introdotte\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/montecarlotennismasters.com\/it\/record-di-presenze-e-novita-introdotte\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/montecarlotennismasters.com\/it\/record-di-presenze-e-novita-introdotte\/#primaryimage","url":"https:\/\/montecarlotennismasters.com\/wp-content\/uploads\/2025\/04\/playersvill-1024x681.jpg","contentUrl":"https:\/\/montecarlotennismasters.com\/wp-content\/uploads\/2025\/04\/playersvill-1024x681.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/montecarlotennismasters.com\/it\/record-di-presenze-e-novita-introdotte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/montecarlotennismasters.com\/it\/"},{"@type":"ListItem","position":2,"name":"Record di presenze e novit\u00e0 introdotte"}]},{"@type":"WebSite","@id":"https:\/\/montecarlotennismasters.com\/#website","url":"https:\/\/montecarlotennismasters.com\/","name":"Rolex Monte-Carlo Masters","description":"11-19 aprile 2020","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/montecarlotennismasters.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/montecarlotennismasters.com\/#\/schema\/person\/2ba3ea68fef415c502ae40903053fada","name":"Eric SILVESTRO","url":"https:\/\/montecarlotennismasters.com\/it\/author\/esilvestro\/"}]}},"_links":{"self":[{"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/posts\/86720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/comments?post=86720"}],"version-history":[{"count":0,"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/posts\/86720\/revisions"}],"wp:attachment":[{"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/media?parent=86720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/categories?post=86720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/montecarlotennismasters.com\/it\/wp-json\/wp\/v2\/tags?post=86720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}